{"id":2026,"date":"2024-12-12T13:14:22","date_gmt":"2024-12-12T18:14:22","guid":{"rendered":"https:\/\/gloriacoach.com\/coaching-vs-therapy\/"},"modified":"2026-06-18T13:30:07","modified_gmt":"2026-06-18T17:30:07","slug":"le-coaching-vs-la-therapie","status":"publish","type":"page","link":"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/","title":{"rendered":"Le coaching vs. la th\u00e9rapie"},"content":{"rendered":"\n<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_0 et_pb_row et_block_row\"><div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_heading_0 et_pb_heading et_pb_module et_block_module\"><div class=\"et_pb_heading_container\"><h1 class=\"et_pb_module_header\">Le coaching vs. la th\u00e9rapie<\/h1><\/div><\/div><\/div><\/div><div class=\"et_pb_row_1 et_pb_row et_pb_gutters4 et_block_row\"><div class=\"et_pb_column_1 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><h2>Qu'est-ce que le coaching ?<\/h2>\n<p>L'ICF d\u00e9finit le <strong>coaching<\/strong> comme un partenariat avec les clients dans un processus de r\u00e9flexion et de cr\u00e9ativit\u00e9 qui les inspire \u00e0 maximiser leur potentiel personnel et professionnel.<br \/>Le coaching se concentre sur la vision, le succ\u00e8s, le pr\u00e9sent et l'avancement vers l'avenir<\/p>\n<\/div><\/div><\/div><div class=\"et_pb_column_2 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><h2>Qu'est-ce que la th\u00e9rapie ?<\/h2>\n<p>La <strong>th\u00e9rapie<\/strong>, quant \u00e0 elle, met l'accent sur la psychopathologie, les \u00e9motions et le pass\u00e9 pour comprendre le pr\u00e9sent, et travaille davantage sur le d\u00e9veloppement de comp\u00e9tences pour g\u00e9rer les \u00e9motions ou les probl\u00e8mes pass\u00e9s.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_2 et_pb_row et_block_row\"><div class=\"et_pb_column_3 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><h3>Le coaching puise des \u00e9l\u00e9ments tant dans le conseil que dans la th\u00e9rapie.<br \/>\n<\/h3>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_3 et_pb_row et_pb_equal_columns et_pb_gutters4 et_block_row\"><div class=\"et_pb_column_4 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><h4>Coaching<\/h4>\n<ul>\n<li>En coaching ex\u00e9cutif ou de leadership, vise \u00e0 d\u00e9velopper les comp\u00e9tences et comportements pour atteindre des objectifs dans un cadre professionnel<\/li>\n<li>Accompagne dans la d\u00e9finition de ces objectifs, g\u00e9n\u00e9ralement pour une dur\u00e9e d\u00e9termin\u00e9e<\/li>\n<li>Suit une d\u00e9ontologie propre au coaching<\/li>\n<li>Met l'accent sur le futur, bien que l\u2019on puisse explorer des sch\u00e9mas de comportements du pass\u00e9<\/li>\n<li>Consiste en une collaboration avec les clients en tant que partenaires \u00e9gaux<\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"et_pb_column_5 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><h4>Th\u00e9rapie<\/h4>\n<ul>\n<li>Soutient les clients confront\u00e9s \u00e0 des probl\u00e8mes de sant\u00e9 mentale, avec un d\u00e9lai ouvert<\/li>\n<li>Est guid\u00e9e par les normes \u00e9thiques m\u00e9dicales<\/li>\n<li>Se base sur un mod\u00e8le m\u00e9dical o\u00f9 on met l'accent sur le diagnostic et la pathologie<\/li>\n<li>Se concentre sur les exp\u00e9riences pass\u00e9es<\/li>\n<li>Met l\u2019accent sur le d\u00e9veloppement des comp\u00e9tences pour le succ\u00e8s \u00e9motionnel<\/li>\n<li>Repose sur une relation expert(e) et patient(e)<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_4 et_pb_row et_block_row\"><div class=\"et_pb_column_6 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><ul>\n<li>Encourage l'exploration des exp\u00e9riences personnelles<\/li>\n<li>Aborde des d\u00e9fis complexes dans la vie professionnelle et personnelle<\/li>\n<li>Met l'accent sur la transformation du comportement individuel<\/li>\n<li>Consiste \u00e0 poser les bonnes questions<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_5 et_pb_row et_pb_gutters1 et_block_row\"><div class=\"et_pb_column_7 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><h4>Coaching<\/h4>\n<ul>\n<li>En coaching ex\u00e9cutif ou de leadership, vise \u00e0 d\u00e9velopper les comp\u00e9tences et comportements pour atteindre des objectifs dans un cadre professionnel<\/li>\n<li>Accompagne dans la d\u00e9finition de ces objectifs, g\u00e9n\u00e9ralement pour une dur\u00e9e d\u00e9termin\u00e9e<\/li>\n<li>Suit une d\u00e9ontologie propre au coaching<\/li>\n<li>Met l'accent sur le futur, bien que l\u2019on puisse explorer des sch\u00e9mas de comportements du pass\u00e9<\/li>\n<li>Consiste en une collaboration avec les clients en tant que partenaires \u00e9gaux<\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"et_pb_column_8 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><ul>\n<li>Encourage l'exploration des exp\u00e9riences personnelles<\/li>\n<li>Aborde des d\u00e9fis complexes dans la vie professionnelle et personnelle<\/li>\n<li>Met l'accent sur la transformation du comportement individuel<\/li>\n<li>Consiste \u00e0 poser les bonnes questions<\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"et_pb_column_9 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><h4>Th\u00e9rapie<\/h4>\n<ul>\n<li>Soutient les clients confront\u00e9s \u00e0 des probl\u00e8mes de sant\u00e9 mentale, avec un d\u00e9lai ouvert<\/li>\n<li>Est guid\u00e9e par les normes \u00e9thiques m\u00e9dicales<\/li>\n<li>Se base sur un mod\u00e8le m\u00e9dical o\u00f9 on met l'accent sur le diagnostic et la pathologie<\/li>\n<li>Se concentre sur les exp\u00e9riences pass\u00e9es<\/li>\n<li>Met l\u2019accent sur le d\u00e9veloppement des comp\u00e9tences pour le succ\u00e8s \u00e9motionnel<\/li>\n<li>Repose sur une relation expert(e) et patient(e)<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_6 et_pb_row et_block_row\"><div class=\"et_pb_column_10 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Un coach est comme un entra\u00eeneur sportif, tandis qu\u2019un th\u00e9rapeute est comme un m\u00e9decin sp\u00e9cialis\u00e9 en m\u00e9decine du sport.  L\u2019entra\u00eeneur part du principe que l\u2019athl\u00e8te est en bonne sant\u00e9 globale et se concentre sur l\u2019am\u00e9lioration de la condition physique et des performances. Cependant, en cas de suspicion de blessure ou de probl\u00e8me de sant\u00e9, l\u2019entra\u00eeneur redirigera l\u2019athl\u00e8te vers le m\u00e9decin de l\u2019\u00e9quipe.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_7 et_pb_row et_block_row\"><div class=\"et_pb_column_11 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Inspir\u00e9 de l'article de Harvard Business Review \"What Can Coaches Do for You?\" par Diane Coutu et Carol Kauffman<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_8 et_pb_row et_block_row\"><div class=\"et_pb_column_12 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_cta_0 et_pb_promo et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_promo_description\"><h2 class=\"et_pb_module_header\">Vous souhaitez savoir si Gloria vous convient ?<\/h2><\/div><div class=\"et_pb_button_wrapper\"><a class=\"et_pb_button et_pb_promo_button\" href=\"\/fr\/contact\/\">Contactez-nous<\/a><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2026","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le coaching vs. la th\u00e9rapie - Gloria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le coaching vs. la th\u00e9rapie - Gloria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/\" \/>\n<meta property=\"og:site_name\" content=\"Gloria\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T17:30:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gloriacoach.com\/wp-content\/uploads\/2024\/06\/cropped-icon-G.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/le-coaching-vs-la-therapie\\\/\",\"url\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/le-coaching-vs-la-therapie\\\/\",\"name\":\"Le coaching vs. la th\u00e9rapie - Gloria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-12-12T18:14:22+00:00\",\"dateModified\":\"2026-06-18T17:30:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/le-coaching-vs-la-therapie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/le-coaching-vs-la-therapie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/le-coaching-vs-la-therapie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le coaching vs. la th\u00e9rapie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/\",\"name\":\"Gloria\",\"description\":\"Coaching at the intersection of leadership and women\u2019s health\",\"publisher\":{\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/#organization\",\"name\":\"Gloria\",\"url\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gloriacoach.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-icon-G.png\",\"contentUrl\":\"https:\\\/\\\/gloriacoach.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-icon-G.png\",\"width\":512,\"height\":512,\"caption\":\"Gloria\"},\"image\":{\"@id\":\"https:\\\/\\\/gloriacoach.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le coaching vs. la th\u00e9rapie - Gloria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/","og_locale":"fr_FR","og_type":"article","og_title":"Le coaching vs. la th\u00e9rapie - Gloria","og_url":"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/","og_site_name":"Gloria","article_modified_time":"2026-06-18T17:30:07+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/gloriacoach.com\/wp-content\/uploads\/2024\/06\/cropped-icon-G.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/","url":"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/","name":"Le coaching vs. la th\u00e9rapie - Gloria","isPartOf":{"@id":"https:\/\/gloriacoach.com\/fr\/#website"},"datePublished":"2024-12-12T18:14:22+00:00","dateModified":"2026-06-18T17:30:07+00:00","breadcrumb":{"@id":"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gloriacoach.com\/fr\/le-coaching-vs-la-therapie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gloriacoach.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le coaching vs. la th\u00e9rapie"}]},{"@type":"WebSite","@id":"https:\/\/gloriacoach.com\/fr\/#website","url":"https:\/\/gloriacoach.com\/fr\/","name":"Gloria","description":"Coaching at the intersection of leadership and women\u2019s health","publisher":{"@id":"https:\/\/gloriacoach.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gloriacoach.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/gloriacoach.com\/fr\/#organization","name":"Gloria","url":"https:\/\/gloriacoach.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gloriacoach.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/gloriacoach.com\/wp-content\/uploads\/2024\/06\/cropped-icon-G.png","contentUrl":"https:\/\/gloriacoach.com\/wp-content\/uploads\/2024\/06\/cropped-icon-G.png","width":512,"height":512,"caption":"Gloria"},"image":{"@id":"https:\/\/gloriacoach.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gloriacoach.com\/fr\/wp-json\/wp\/v2\/pages\/2026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gloriacoach.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gloriacoach.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gloriacoach.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gloriacoach.com\/fr\/wp-json\/wp\/v2\/comments?post=2026"}],"version-history":[{"count":4,"href":"https:\/\/gloriacoach.com\/fr\/wp-json\/wp\/v2\/pages\/2026\/revisions"}],"predecessor-version":[{"id":3299,"href":"https:\/\/gloriacoach.com\/fr\/wp-json\/wp\/v2\/pages\/2026\/revisions\/3299"}],"wp:attachment":[{"href":"https:\/\/gloriacoach.com\/fr\/wp-json\/wp\/v2\/media?parent=2026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}